{"id":100191,"date":"2023-12-07T14:38:48","date_gmt":"2023-12-07T13:38:48","guid":{"rendered":"https:\/\/maperle.fr\/?post_type=product&#038;p=100191"},"modified":"2024-06-02T16:42:43","modified_gmt":"2024-06-02T15:42:43","slug":"soleil","status":"publish","type":"product","link":"https:\/\/maperle.fr\/en\/produit\/soleil\/","title":{"rendered":"Soleil"},"content":{"rendered":"<p>Pi\u00e8ce unique et rare, cette chaine en argent avec ses perles de culture dor\u00e9es fera l&#8217;unanimit\u00e9 ! Succ\u00e8s garanti car ces perles sont parmi les plus rares et donc les plus chers au monde ! (longueur 43 cm)<\/p>\n<p>Les photos permettent de mieux visualiser les bijoux \u00e0 titre indicatif uniquement.<br \/>\nChaque perle de culture et chaque pierre sont uniques par leur forme, couleurs et nuances.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"width: 960px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-100191-1\" width=\"960\" height=\"960\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/maperle.fr\/wp-content\/uploads\/2023\/12\/SKU011.mp4?_=1\" \/><a href=\"https:\/\/maperle.fr\/wp-content\/uploads\/2023\/12\/SKU011.mp4\">https:\/\/maperle.fr\/wp-content\/uploads\/2023\/12\/SKU011.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pi\u00e8ce unique et rare, cette chaine en argent avec ses perles de culture dor\u00e9es fera l&#8217;unanimit\u00e9 ! Succ\u00e8s garanti car ces perles sont parmi les plus rares et donc les plus chers au monde ! (longueur 43 cm) Les photos permettent de mieux visualiser les bijoux \u00e0 titre indicatif uniquement. Chaque perle de culture et [&hellip;]<\/p>\n","protected":false},"featured_media":101223,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[164,47,94,163,127,130,132,133],"product_tag":[],"class_list":["post-100191","product","type-product","status-publish","has-post-thumbnail","product_cat-categories","product_cat-collier","product_cat-perle","product_cat-collection","product_cat-moderne","product_cat-luxe","product_cat-materiaux","product_cat-argent-925","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Soleil - Ma Perle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maperle.fr\/en\/produit\/soleil\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soleil - Ma Perle\" \/>\n<meta property=\"og:description\" content=\"Pi\u00e8ce unique et rare, cette chaine en argent avec ses perles de culture dor\u00e9es fera l&#8217;unanimit\u00e9 ! Succ\u00e8s garanti car ces perles sont parmi les plus rares et donc les plus chers au monde ! (longueur 43 cm) Les photos permettent de mieux visualiser les bijoux \u00e0 titre indicatif uniquement. Chaque perle de culture et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maperle.fr\/en\/produit\/soleil\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma Perle\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-02T15:42:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maperle.fr\/wp-content\/uploads\/2024\/05\/IMG-20240523-WA0137.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1546\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/maperle.fr\/en\/produit\/soleil\/\",\"url\":\"https:\/\/maperle.fr\/en\/produit\/soleil\/\",\"name\":\"Soleil - Ma Perle\",\"isPartOf\":{\"@id\":\"https:\/\/maperle.fr\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/maperle.fr\/en\/produit\/soleil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/maperle.fr\/en\/produit\/soleil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/maperle.fr\/wp-content\/uploads\/2024\/05\/IMG-20240523-WA0137.jpg\",\"datePublished\":\"2023-12-07T13:38:48+00:00\",\"dateModified\":\"2024-06-02T15:42:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/maperle.fr\/en\/produit\/soleil\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/maperle.fr\/en\/produit\/soleil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/maperle.fr\/en\/produit\/soleil\/#primaryimage\",\"url\":\"https:\/\/maperle.fr\/wp-content\/uploads\/2024\/05\/IMG-20240523-WA0137.jpg\",\"contentUrl\":\"https:\/\/maperle.fr\/wp-content\/uploads\/2024\/05\/IMG-20240523-WA0137.jpg\",\"width\":1546,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/maperle.fr\/en\/produit\/soleil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/maperle.fr\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/maperle.fr\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Soleil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/maperle.fr\/en\/#website\",\"url\":\"https:\/\/maperle.fr\/en\/\",\"name\":\"Ma Perle\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/maperle.fr\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/maperle.fr\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/maperle.fr\/en\/#organization\",\"name\":\"Ma Perle\",\"url\":\"https:\/\/maperle.fr\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/maperle.fr\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/maperle.fr\/wp-content\/uploads\/2023\/11\/cropped-maperle-logo.png\",\"contentUrl\":\"https:\/\/maperle.fr\/wp-content\/uploads\/2023\/11\/cropped-maperle-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Ma Perle\"},\"image\":{\"@id\":\"https:\/\/maperle.fr\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soleil - Ma Perle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maperle.fr\/en\/produit\/soleil\/","og_locale":"en_US","og_type":"article","og_title":"Soleil - Ma Perle","og_description":"Pi\u00e8ce unique et rare, cette chaine en argent avec ses perles de culture dor\u00e9es fera l&#8217;unanimit\u00e9 ! Succ\u00e8s garanti car ces perles sont parmi les plus rares et donc les plus chers au monde ! (longueur 43 cm) Les photos permettent de mieux visualiser les bijoux \u00e0 titre indicatif uniquement. Chaque perle de culture et [&hellip;]","og_url":"https:\/\/maperle.fr\/en\/produit\/soleil\/","og_site_name":"Ma Perle","article_modified_time":"2024-06-02T15:42:43+00:00","og_image":[{"width":1546,"height":1600,"url":"https:\/\/maperle.fr\/wp-content\/uploads\/2024\/05\/IMG-20240523-WA0137.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maperle.fr\/en\/produit\/soleil\/","url":"https:\/\/maperle.fr\/en\/produit\/soleil\/","name":"Soleil - Ma Perle","isPartOf":{"@id":"https:\/\/maperle.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maperle.fr\/en\/produit\/soleil\/#primaryimage"},"image":{"@id":"https:\/\/maperle.fr\/en\/produit\/soleil\/#primaryimage"},"thumbnailUrl":"https:\/\/maperle.fr\/wp-content\/uploads\/2024\/05\/IMG-20240523-WA0137.jpg","datePublished":"2023-12-07T13:38:48+00:00","dateModified":"2024-06-02T15:42:43+00:00","breadcrumb":{"@id":"https:\/\/maperle.fr\/en\/produit\/soleil\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maperle.fr\/en\/produit\/soleil\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maperle.fr\/en\/produit\/soleil\/#primaryimage","url":"https:\/\/maperle.fr\/wp-content\/uploads\/2024\/05\/IMG-20240523-WA0137.jpg","contentUrl":"https:\/\/maperle.fr\/wp-content\/uploads\/2024\/05\/IMG-20240523-WA0137.jpg","width":1546,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/maperle.fr\/en\/produit\/soleil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/maperle.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/maperle.fr\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Soleil"}]},{"@type":"WebSite","@id":"https:\/\/maperle.fr\/en\/#website","url":"https:\/\/maperle.fr\/en\/","name":"Ma Perle","description":"","publisher":{"@id":"https:\/\/maperle.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maperle.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/maperle.fr\/en\/#organization","name":"Ma Perle","url":"https:\/\/maperle.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maperle.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/maperle.fr\/wp-content\/uploads\/2023\/11\/cropped-maperle-logo.png","contentUrl":"https:\/\/maperle.fr\/wp-content\/uploads\/2023\/11\/cropped-maperle-logo.png","width":512,"height":512,"caption":"Ma Perle"},"image":{"@id":"https:\/\/maperle.fr\/en\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maperle.fr\/en\/wp-json\/wp\/v2\/product\/100191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maperle.fr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/maperle.fr\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/maperle.fr\/en\/wp-json\/wp\/v2\/comments?post=100191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maperle.fr\/en\/wp-json\/wp\/v2\/media\/101223"}],"wp:attachment":[{"href":"https:\/\/maperle.fr\/en\/wp-json\/wp\/v2\/media?parent=100191"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/maperle.fr\/en\/wp-json\/wp\/v2\/product_brand?post=100191"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/maperle.fr\/en\/wp-json\/wp\/v2\/product_cat?post=100191"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/maperle.fr\/en\/wp-json\/wp\/v2\/product_tag?post=100191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}